{"id":772,"date":"2018-11-25T19:20:09","date_gmt":"2018-11-25T18:20:09","guid":{"rendered":"http:\/\/www.chiesavaldesepalermo.it\/pa\/?p=772"},"modified":"2018-11-25T19:20:09","modified_gmt":"2018-11-25T18:20:09","slug":"il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin","status":"publish","type":"post","link":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/","title":{"rendered":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin"},"content":{"rendered":"<p><b>Predicazione di domenica 25 novembre 2018 sul testo di Isaia 65,17-25, a cura del pastore Peter Ciaccio, in occasione della Domenica liturgica dell&#8217;Eternit\u00e0 e della Giornata internazionale contro la violenza sulle donne.<\/b><\/p>\n<p><em>\u00abPoich\u00e9, ecco, io creo nuovi cieli e una nuova terra; non ci si ricorder\u00e0 pi\u00f9 delle cose di prima; esse non torneranno pi\u00f9 in memoria. Gioite, s\u00ec, esultate in eterno per quanto io sto per creare; poich\u00e9, ecco, io creo Gerusalemme per il gaudio, e il suo popolo per la gioia. Io esulter\u00f2 a motivo di Gerusalemme e gioir\u00f2 del mio popolo; l\u00e0 non si udranno pi\u00f9 voci di pianto n\u00e9 grida d\u2019angoscia; non ci sar\u00e0 pi\u00f9, in avvenire, bimbo nato per pochi giorni, n\u00e9 vecchio che non compia il numero dei suoi anni; chi morir\u00e0 a cent&#8217;anni morir\u00e0 giovane e il peccatore sar\u00e0 colpito dalla maledizione a cent\u2019anni. Essi costruiranno case e le abiteranno; pianteranno vigne e ne mangeranno il frutto. Non costruiranno pi\u00f9 perch\u00e9 un altro abiti, non pianteranno pi\u00f9 perch\u00e9 un altro mangi; poich\u00e9 i giorni del mio popolo saranno come i giorni degli alberi; i miei eletti godranno a lungo l&#8217;opera delle loro mani. Non si affaticheranno invano, non avranno pi\u00f9 figli per vederli morire all\u2019improvviso; poich\u00e9 saranno la discendenza dei benedetti del Signore e i loro rampolli staranno con essi. Avverr\u00e0 che, prima che m&#8217;invochino, io risponder\u00f2; parleranno ancora, che gi\u00e0 li avr\u00f2 esauditi. Il lupo e l&#8217;agnello pascoleranno assieme, il leone manger\u00e0 il foraggio come il bue, e il serpente si nutrir\u00e0 di polvere. Non si far\u00e0 n\u00e9 male n\u00e9 danno su tutto il mio monte santo\u00bb, dice il Signore.<\/em><\/p>\n<p><a href=\"http:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-773\" src=\"http:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg\" alt=\"\" width=\"640\" height=\"373\" srcset=\"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg 640w, https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin-300x175.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Quando ero piccolo, mi ricordo che passavo il tempo a leggere Topolino. Non avevo un briciolo della vita sociale che ho adesso, non avevo molti amici, ma ero felice. Io e il mio Topolino: non mi mancava niente. Poi sono cresciuto un poco e ho cominciato ad avere diversi amici. Giocavamo a pallone per strada. C\u2019era una casa, ovviamente una casa abusiva, oltre la met\u00e0 del mio quartiere era fatta di case abusive. In questa casa in particolare, che si trovava al lato della strada dove giocavamo, finivano sempre i nostri palloni, dei SuperTele che compravamo a due-tremila lire. Avevamo inventato la leggenda che questa casa avesse uno scantinato, dove il padrone custodiva tutti i palloni che finivano l\u00ec e che non ci restituiva. Erano bei tempi.<\/p>\n<p>Questi sono solo due dei ricordi belli della mia vita. Grazie a Dio, ce ne sono molti altri. Mi \u00e8 piaciuto ricordarli, condividerli con voi questa mattina. Eppure, il testo di oggi ci dice: \u00abnon ci si ricorder\u00e0 pi\u00f9 delle cose di prima, esse non torneranno pi\u00f9 in memoria\u00bb. Perch\u00e9?<\/p>\n<p>Ci pare ovvio che il testo parli delle cose brutte. Il popolo cui si rivolge il profeta \u00e8 un popolo che ha sofferto guerra, sconfitta e deportazione, avvenimenti che \u00e8 forse meglio dimenticare, la cui memoria potrebbe paralizzarci, cambiarci, mutare il corso della nostra vita. Come fare a vivere una vita nuova se la vita vecchia \u00e8 un fantasma, uno spettro presente nella mia esistenza?<\/p>\n<p>Noi abbiamo trovato un metodo, che gli psicologi chiamano rimozione o memoria selettiva: ricordo solo quello che voglio ricordare. Spesso lo facciamo inconsciamente, automaticamente, senza nemmeno pensarci. Altre volte, invece, ci sforziamo attivamente a rimuovere gli eventi dolorosi del passato. E lo consigliamo agli altri: cosa diciamo, ad esempio, a chi ha vissuto un grande lutto? \u00abNon ci pensare\u00bb. Non ci pensare e quel passato brutto, quell\u2019episodio, quella ferita sar\u00e0 sanata.<\/p>\n<p>Il profeta ci dice che le cose passate non saranno ricordate. Siamo sicuri che si tratti, per\u00f2, solo delle cose brutte?<\/p>\n<p>Nell\u2019operazione di rimozione, a volte necessaria per carit\u00e0, noi infatti corriamo un rischio: l\u2019idealizzazione del passato. Un\u2019idealizzazione che rischia di rovinare la vita nostra e delle altre persone. Parlo dei \u201cbei tempi andati\u201d, che poi alla fine erano probabilmente non propriamente \u201cbelli\u201d, ma semplicemente momenti in cui c\u2019era l\u2019energia della giovent\u00f9, la prospettiva di un futuro, la protezione dei genitori, ma c\u2019erano anche ombre.<\/p>\n<p>Oggi, in nome dei \u201cbei tempi andati\u201d, viviamo spesso bloccati in un passato idealizzato, quel passato in cui giocavi a pallone per strada e ti dimentichi che qualcuno finiva sotto una macchina, ti dimentichi che giocavi per strada perch\u00e9 non c\u2019erano campi di calcetto o perch\u00e9 non avevi soldi per affittarlo. Ti dimentichi che eri felice perch\u00e9, nonostante tutto, nonostante tutto, eri riuscito a giocare. E ti dimentichi di chi era escluso dai tuoi giochi.<\/p>\n<p>Non ricordo di avere avuto amici omosessuali con cui giocare, per fare un esempio. Non che non ci fossero, ma non si giocava con loro, un po\u2019 perch\u00e9 si isolavano, un po\u2019 perch\u00e9 erano diversi. Non giocavo neanche con le bambine e le ragazze. No, per carit\u00e0, giocavo solo coi maschi. Le bambine e le ragazze erano altro, erano \u201canimali strani\u201d, diverse, affascinanti, terre di conquista (quando andava bene), insomma, \u201coggetti\u201d, non \u201csoggetti\u201d alla pari.<\/p>\n<p>Nei bei tempi andati c\u2019era il germe dell\u2019omofobia e della misoginia, in quella spensieratezza c\u2019era il germe della violenza. Non \u00e8 un caso che i pifferai di Hamelin del mondo sono quelli che ti seducono parlando dei bei tempi andati, che stuzzicano la tua nostalgia, che ti fanno rimpiangere un mondo che non c\u2019\u00e8 pi\u00f9, aumentando il tuo disprezzo per il presente, quel presente di problemi adulti, dove non ci sono pi\u00f9 mamma e pap\u00e0 a proteggerti, dove la responsabilit\u00e0 di andare avanti pesa come un macigno.<\/p>\n<p>Ricordate il pifferaio di Hamelin? Era il protagonista di quella fiaba dove un musicista catturava con le meravigliose e magiche note del suo flauto tutti i topi che infestavano la cittadina di Hamelin. Gli abitanti decidono di non pagarlo per il servizio e il pifferaio li punisce: suona il flauto e cattura tutti i bambini del paese che lo seguono fino a sparire (secondo alcune versioni, muoiono).<\/p>\n<p>Quale melodia suonano i pifferai di Hamelin a noi contemporanei? \u00abTi ricordi quando tutti parlavano la tua lingua, quando erano tutti bianchi, quando non c\u2019erano tutti questi gay, quando le donne stavano al loro posto, quando si poteva parlare tranquillamente senza questa paranoia del linguaggio inclusivo, quando questa mania del politicamente corretto non esisteva? Ti ricordi che bello? Ti ricordi quando c\u2019era la lira e con mille lire, gli attuali 50 centesimi, compravi un gelato, quando con diecimila lire passavi la serata? Ti ricordi quando c\u2019era musica che si capiva, che ti piaceva? Ti ricordi quando giocavi a pallone per strada con gli amici e non succedeva niente, quando passavi il tempo a leggere fumetti, senza preoccupazioni alcune? Ecco, quei bei tempi possiamo farli tornare insieme\u00bb.<br \/>\nQuesto ci dicono i pifferai di Hamelin di oggi, che seducono per portare le proprie vittime alla violenza, alla distruzione, alla morte.<\/p>\n<p>Proprio il contrario, invece, ci dice e continua a dirci oggi il profeta. Tutto questo non torner\u00e0. Non, per\u00f2, perch\u00e9 andiamo verso la rovina, ma perch\u00e9 andiamo verso il sogno di Dio. \u00abEcco, io creo nuovi cieli e una nuova terra\u00bb. Nuovi. Nuovi cieli e una nuova terra. Non i bei tempi andati, non il difficile presente di responsabilit\u00e0, non il futuro incerto, ma nuovi cieli e una nuova terra.<\/p>\n<p>Solo mantenendo questa prospettiva, allineando il nostro punto di vista a quello che ci offre Dio, solo cos\u00ec saremo resi immuni dal suono suadente degli odierni pifferai di Hamelin.<\/p>\n<p>\u00abNon costruiranno pi\u00f9 perch\u00e9 un altro abiti, non pianteranno pi\u00f9 perch\u00e9 un altro mangi\u00bb: non ci saranno pi\u00f9 furti, sopraffazioni, abusi n\u00e9 arroganze del potente di turno. \u00abIl lupo e l&#8217;agnello pascoleranno assieme, il leone manger\u00e0 il foraggio come il bue, e il serpente si nutrir\u00e0 di polvere\u00bb. Significa che arriver\u00e0 un giorno in cui non ci saranno pi\u00f9 prede e predatori, in cui non ci sar\u00e0 pi\u00f9 violenza contro le donne, non ci sar\u00e0 pi\u00f9 violenza contro uno straniero, un diverso, un omosessuale, un nero. Non ci saranno pi\u00f9. Altro che bei tempi andati, altro che nostalgia!<\/p>\n<p>Prima di chiudere, un pensiero oggi va a Silvia Romano, la giovane volontaria rapita in Kenya. Non sappiamo cosa sta vivendo in questo momento. Sappiamo molti dicono di lei, qui, nel nostro paese. Un\u2019incosciente, una che ci coster\u00e0 un sacco di soldi in riscatto, una che si \u00e8 fatta bella ad aiutare i poveri in Kenya quando avrebbe potuto aiutare i poveri qui, una che se l\u2019\u00e8 cercata. No, \u00e8 una donna che ha creduto che i bei tempi andati potessero essere dimenticati, una donna che ha creduto che si possa costruire un nuovo mondo, con nuove relazioni, con la solidariet\u00e0 che prende il posto della violenza. Non la conosco, non so se sia credente, ma il suo sogno \u00e8 vicino al sogno di Dio. E non importa che il lupo ha catturato l\u2019agnello. Importa che l\u2019agnello crede che un giorno il lupo non lo catturer\u00e0 pi\u00f9. Importa che l\u2019agnello crede che non c\u2019\u00e8 bisogno di diventare lupi per cambiare le cose. Non \u00e8 un caso che le masse ammaliate dal suadente richiamo degli odierni pifferai di Hamelin disprezzino chi sogna il sogno di Dio, invece di rimpiangere i bei tempi andati in cui ognuno stava e restava a casa sua.<\/p>\n<p>E noi, oggi, rispondiamo al sogno di Dio con la preghiera. Preghiamo per Silvia, preghiamo per tutte le donne che subiscono violenza. E preghiamo con una consapevolezza diversa, perch\u00e9 l\u2019annuncio del profeta oggi ci dice: \u00abAvverr\u00e0 che, prima che m&#8217;invochino, io risponder\u00f2; parleranno ancora, che gi\u00e0 li avr\u00f2 esauditi\u00bb.<\/p>\n<p>Amen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Predicazione di domenica 25 novembre 2018 sul testo di Isaia 65,17-25, a cura del pastore Peter Ciaccio, in occasione della Domenica liturgica dell&#8217;Eternit\u00e0 e della Giornata internazionale contro la violenza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":773,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-772","post","type-post","status-publish","format-standard","has-post-thumbnail","category-predicazioni","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo\" \/>\n<meta property=\"og:description\" content=\"Predicazione di domenica 25 novembre 2018 sul testo di Isaia 65,17-25, a cura del pastore Peter Ciaccio, in occasione della Domenica liturgica dell&#8217;Eternit\u00e0 e della Giornata internazionale contro la violenza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/\" \/>\n<meta property=\"og:site_name\" content=\"Chiesa Valdese Palermo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiesavaldese.dipalermo\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-25T18:20:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Peter Ciaccio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ValdesePa\" \/>\n<meta name=\"twitter:site\" content=\"@ValdesePa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Peter Ciaccio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/\"},\"author\":{\"name\":\"Peter Ciaccio\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#\\\/schema\\\/person\\\/779bfd48e74274424d076bd839792e66\"},\"headline\":\"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin\",\"datePublished\":\"2018-11-25T18:20:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/\"},\"wordCount\":1594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Pied-Piper-of-Hamelin.jpg\",\"articleSection\":[\"Predicazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/\",\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/\",\"name\":\"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Pied-Piper-of-Hamelin.jpg\",\"datePublished\":\"2018-11-25T18:20:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Pied-Piper-of-Hamelin.jpg\",\"contentUrl\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Pied-Piper-of-Hamelin.jpg\",\"width\":640,\"height\":373},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#website\",\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/\",\"name\":\"Chiesa Valdese Palermo\",\"description\":\"Portale online della chiesa valdese di Palermo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#organization\",\"name\":\"Chiesa Valdese di Palermo\",\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/chiesa-valdese-min-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/chiesa-valdese-min-scaled.jpg\",\"width\":2560,\"height\":1570,\"caption\":\"Chiesa Valdese di Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiesavaldese.dipalermo\\\/\",\"https:\\\/\\\/x.com\\\/ValdesePa\",\"https:\\\/\\\/it.pinterest.com\\\/chiesavaldesepalermo\\\/\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Chiesa_evangelica_valdese#\\\/media\\\/File:Palermo-Chiesa-Valdese-bjs2007-01.jpg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/#\\\/schema\\\/person\\\/779bfd48e74274424d076bd839792e66\",\"name\":\"Peter Ciaccio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g\",\"caption\":\"Peter Ciaccio\"},\"url\":\"https:\\\/\\\/www.chiesavaldesepalermo.it\\\/pa\\\/author\\\/pciaccio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/","og_locale":"it_IT","og_type":"article","og_title":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo","og_description":"Predicazione di domenica 25 novembre 2018 sul testo di Isaia 65,17-25, a cura del pastore Peter Ciaccio, in occasione della Domenica liturgica dell&#8217;Eternit\u00e0 e della Giornata internazionale contro la violenza [&hellip;]","og_url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/","og_site_name":"Chiesa Valdese Palermo","article_publisher":"https:\/\/www.facebook.com\/chiesavaldese.dipalermo\/","article_published_time":"2018-11-25T18:20:09+00:00","og_image":[{"width":640,"height":373,"url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg","type":"image\/jpeg"}],"author":"Peter Ciaccio","twitter_card":"summary_large_image","twitter_creator":"@ValdesePa","twitter_site":"@ValdesePa","twitter_misc":{"Scritto da":"Peter Ciaccio","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#article","isPartOf":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/"},"author":{"name":"Peter Ciaccio","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#\/schema\/person\/779bfd48e74274424d076bd839792e66"},"headline":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin","datePublished":"2018-11-25T18:20:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/"},"wordCount":1594,"commentCount":0,"publisher":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#organization"},"image":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg","articleSection":["Predicazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/","url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/","name":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin - Chiesa Valdese Palermo","isPartOf":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#primaryimage"},"image":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg","datePublished":"2018-11-25T18:20:09+00:00","breadcrumb":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#primaryimage","url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg","contentUrl":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2018\/11\/Pied-Piper-of-Hamelin.jpg","width":640,"height":373},{"@type":"BreadcrumbList","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/il-sogno-di-dio-contrapposto-agli-odierni-pifferai-di-hamelin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chiesavaldesepalermo.it\/pa\/"},{"@type":"ListItem","position":2,"name":"Il sogno di Dio contrapposto agli odierni pifferai di Hamelin"}]},{"@type":"WebSite","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#website","url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/","name":"Chiesa Valdese Palermo","description":"Portale online della chiesa valdese di Palermo","publisher":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chiesavaldesepalermo.it\/pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#organization","name":"Chiesa Valdese di Palermo","url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#\/schema\/logo\/image\/","url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2021\/01\/chiesa-valdese-min-scaled.jpg","contentUrl":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-content\/uploads\/2021\/01\/chiesa-valdese-min-scaled.jpg","width":2560,"height":1570,"caption":"Chiesa Valdese di Palermo"},"image":{"@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiesavaldese.dipalermo\/","https:\/\/x.com\/ValdesePa","https:\/\/it.pinterest.com\/chiesavaldesepalermo\/","https:\/\/it.wikipedia.org\/wiki\/Chiesa_evangelica_valdese#\/media\/File:Palermo-Chiesa-Valdese-bjs2007-01.jpg"]},{"@type":"Person","@id":"https:\/\/www.chiesavaldesepalermo.it\/pa\/#\/schema\/person\/779bfd48e74274424d076bd839792e66","name":"Peter Ciaccio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/03620a5901222cea7c4f989168aa516457e976d18873c52de1efd8c5288e437e?s=96&d=mm&r=g","caption":"Peter Ciaccio"},"url":"https:\/\/www.chiesavaldesepalermo.it\/pa\/author\/pciaccio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/posts\/772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/comments?post=772"}],"version-history":[{"count":2,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/posts\/772\/revisions"}],"predecessor-version":[{"id":775,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/posts\/772\/revisions\/775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/media\/773"}],"wp:attachment":[{"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/media?parent=772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/categories?post=772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiesavaldesepalermo.it\/pa\/wp-json\/wp\/v2\/tags?post=772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}